{"id":7101,"date":"2025-10-07T09:19:06","date_gmt":"2025-10-07T09:19:06","guid":{"rendered":"https:\/\/www.formaticbarcelona.com\/?p=7101"},"modified":"2025-10-11T10:34:24","modified_gmt":"2025-10-11T10:34:24","slug":"formacion-secretariado-internacional-de-alta-direccion","status":"publish","type":"post","link":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/","title":{"rendered":"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":7104,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[229],"tags":[364,294,345,284],"class_list":["post-7101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diploma-de-especializacion","tag-curso-secretariado-alta-direccion","tag-cursos-eufb","tag-eufb-estudiar","tag-eufb-formatic","study_type-diplomas-de-especializacion","thematic-comunicacion","thematic-empresa-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EUFB | Formaci\u00f3n en secretariado de alta direcci\u00f3n<\/title>\n<meta name=\"description\" content=\"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI | Escuela Universitaria Formatic Barcelona\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EUFB | Formaci\u00f3n en secretariado de alta direcci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI | Escuela Universitaria Formatic Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela Universitaria Formatic Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escola.barna\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T09:19:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-11T10:34:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.formaticbarcelona.com\/wp-content\/uploads\/2025\/10\/curso-secretariado-de-altra-direccion-eufb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FORMATIC BARCELONA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@formaticbarna\" \/>\n<meta name=\"twitter:site\" content=\"@formaticbarna\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FORMATIC BARCELONA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/\"},\"author\":{\"name\":\"FORMATIC BARCELONA\",\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/#\\\/schema\\\/person\\\/83e2d6cc3e0c6492ddd326ff9c6d2f7b\"},\"headline\":\"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI\",\"datePublished\":\"2025-10-07T09:19:06+00:00\",\"dateModified\":\"2025-10-11T10:34:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/\"},\"wordCount\":17,\"image\":{\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/curso-secretariado-de-altra-direccion-eufb.jpg\",\"keywords\":[\"Curso secretariado alta direcci\u00f3n\",\"Cursos EUFB\",\"EUFB estudiar\",\"EUFB Formatic\"],\"articleSection\":[\"Diploma de especializaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/\",\"url\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/\",\"name\":\"EUFB | Formaci\u00f3n en secretariado de alta direcci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/curso-secretariado-de-altra-direccion-eufb.jpg\",\"datePublished\":\"2025-10-07T09:19:06+00:00\",\"dateModified\":\"2025-10-11T10:34:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/#\\\/schema\\\/person\\\/83e2d6cc3e0c6492ddd326ff9c6d2f7b\"},\"description\":\"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI | Escuela Universitaria Formatic Barcelona\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/curso-secretariado-de-altra-direccion-eufb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/curso-secretariado-de-altra-direccion-eufb.jpg\",\"width\":1600,\"height\":772,\"caption\":\"curso secretariado de altra direcci\u00f3n eufb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/formacion-secretariado-internacional-de-alta-direccion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/\",\"name\":\"Escuela Universitaria Formatic Barcelona\",\"description\":\"Estudios de Grado y Dobles Grados \u2013 M\u00e1ster \u2013 Ciclos Formativos de Grado Superior \u2013 Cursos de Tripulante de Cabina de Pasajeros en Barcelona y de Azafatas de Vuelo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/#\\\/schema\\\/person\\\/83e2d6cc3e0c6492ddd326ff9c6d2f7b\",\"name\":\"FORMATIC BARCELONA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05175dad1874823b7b9101278fc7f2651d8cb257fce8bba121e8ec2b8621ea1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05175dad1874823b7b9101278fc7f2651d8cb257fce8bba121e8ec2b8621ea1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05175dad1874823b7b9101278fc7f2651d8cb257fce8bba121e8ec2b8621ea1d?s=96&d=mm&r=g\",\"caption\":\"FORMATIC BARCELONA\"},\"url\":\"https:\\\/\\\/www.formaticbarcelona.com\\\/es\\\/author\\\/ebmo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EUFB | Formaci\u00f3n en secretariado de alta direcci\u00f3n","description":"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI | Escuela Universitaria Formatic Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/","og_locale":"es_ES","og_type":"article","og_title":"EUFB | Formaci\u00f3n en secretariado de alta direcci\u00f3n","og_description":"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI | Escuela Universitaria Formatic Barcelona","og_url":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/","og_site_name":"Escuela Universitaria Formatic Barcelona","article_publisher":"https:\/\/www.facebook.com\/escola.barna","article_published_time":"2025-10-07T09:19:06+00:00","article_modified_time":"2025-10-11T10:34:24+00:00","og_image":[{"width":1600,"height":772,"url":"https:\/\/www.formaticbarcelona.com\/wp-content\/uploads\/2025\/10\/curso-secretariado-de-altra-direccion-eufb.jpg","type":"image\/jpeg"}],"author":"FORMATIC BARCELONA","twitter_card":"summary_large_image","twitter_creator":"@formaticbarna","twitter_site":"@formaticbarna","twitter_misc":{"Escrito por":"FORMATIC BARCELONA","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/#article","isPartOf":{"@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/"},"author":{"name":"FORMATIC BARCELONA","@id":"https:\/\/www.formaticbarcelona.com\/es\/#\/schema\/person\/83e2d6cc3e0c6492ddd326ff9c6d2f7b"},"headline":"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI","datePublished":"2025-10-07T09:19:06+00:00","dateModified":"2025-10-11T10:34:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/"},"wordCount":17,"image":{"@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.formaticbarcelona.com\/wp-content\/uploads\/2025\/10\/curso-secretariado-de-altra-direccion-eufb.jpg","keywords":["Curso secretariado alta direcci\u00f3n","Cursos EUFB","EUFB estudiar","EUFB Formatic"],"articleSection":["Diploma de especializaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/","url":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/","name":"EUFB | Formaci\u00f3n en secretariado de alta direcci\u00f3n","isPartOf":{"@id":"https:\/\/www.formaticbarcelona.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/#primaryimage"},"image":{"@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.formaticbarcelona.com\/wp-content\/uploads\/2025\/10\/curso-secretariado-de-altra-direccion-eufb.jpg","datePublished":"2025-10-07T09:19:06+00:00","dateModified":"2025-10-11T10:34:24+00:00","author":{"@id":"https:\/\/www.formaticbarcelona.com\/es\/#\/schema\/person\/83e2d6cc3e0c6492ddd326ff9c6d2f7b"},"description":"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI | Escuela Universitaria Formatic Barcelona","breadcrumb":{"@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/#primaryimage","url":"https:\/\/www.formaticbarcelona.com\/wp-content\/uploads\/2025\/10\/curso-secretariado-de-altra-direccion-eufb.jpg","contentUrl":"https:\/\/www.formaticbarcelona.com\/wp-content\/uploads\/2025\/10\/curso-secretariado-de-altra-direccion-eufb.jpg","width":1600,"height":772,"caption":"curso secretariado de altra direcci\u00f3n eufb"},{"@type":"BreadcrumbList","@id":"https:\/\/www.formaticbarcelona.com\/es\/formacion-secretariado-internacional-de-alta-direccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.formaticbarcelona.com\/es\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 el secretariado internacional de alta direcci\u00f3n es el rol estrat\u00e9gico del siglo XXI"}]},{"@type":"WebSite","@id":"https:\/\/www.formaticbarcelona.com\/es\/#website","url":"https:\/\/www.formaticbarcelona.com\/es\/","name":"Escuela Universitaria Formatic Barcelona","description":"Estudios de Grado y Dobles Grados \u2013 M\u00e1ster \u2013 Ciclos Formativos de Grado Superior \u2013 Cursos de Tripulante de Cabina de Pasajeros en Barcelona y de Azafatas de Vuelo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.formaticbarcelona.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.formaticbarcelona.com\/es\/#\/schema\/person\/83e2d6cc3e0c6492ddd326ff9c6d2f7b","name":"FORMATIC BARCELONA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/05175dad1874823b7b9101278fc7f2651d8cb257fce8bba121e8ec2b8621ea1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05175dad1874823b7b9101278fc7f2651d8cb257fce8bba121e8ec2b8621ea1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05175dad1874823b7b9101278fc7f2651d8cb257fce8bba121e8ec2b8621ea1d?s=96&d=mm&r=g","caption":"FORMATIC BARCELONA"},"url":"https:\/\/www.formaticbarcelona.com\/es\/author\/ebmo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/posts\/7101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/comments?post=7101"}],"version-history":[{"count":6,"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/posts\/7101\/revisions"}],"predecessor-version":[{"id":7116,"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/posts\/7101\/revisions\/7116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/media\/7104"}],"wp:attachment":[{"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/media?parent=7101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/categories?post=7101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.formaticbarcelona.com\/es\/wp-json\/wp\/v2\/tags?post=7101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}